{"id":106,"count":66,"description":"Der Einsatz vom Endprodukt bis hin zu Einzelkomponenten in der Bahntechnik stellt entlang der gesamten Herstellungskette h\u00f6chste Anspr\u00fcche in Bezug auf die Sicherheit der Bahnkunden und des Personals. Die gr\u00f6\u00dfte Bedrohung ist neben der entstehenden Hitze der Rauch und die damit einhergehenden toxischen Gase in einem brennenden Zug. Um ein m\u00f6gliches Gefahrenpotenzial fr\u00fchzeitig zu erkennen und zu bewerten, gilt es, den Regeln der Europ\u00e4ischen Brandschutznorm nach EN 45545 in Schienenfahrzeugen zu folgen.\r\n\r\nLagra Systemtechnik kennt die Anforderungen der Bahnindustrie sehr gut und bietet neben dem Wissen \u00fcber den Umgang mit der Norm auch geeignete Materialien und Unterst\u00fctzung bei der Auswahl und Zulassung von den notwendigen Komponenten. Somit begleiten wir durch kompetente Beratung unsere Kunden auf dem Weg zu mehr Sicherheit im Schienenverkehr.\r\n\r\nDie aktuelle Bahnnorm EN 45545 beschreibt europaweit einheitlich die brandschutz-technischen Anforderungen aller verwendeten Werkstoffe im Schienenfahrzeugbau, sowohl im Innen- als auch im Au\u00dfenbereich. Die Anforderungen an das Brandverhalten solcher Materialien und Komponenten sind in diesem Umfeld besonders streng.\r\n\r\nDas Produktspektrum von Lagra umfasst neben den Wellrohren aus PA6 und PA12 auch die dazugeh\u00f6rigen Wellrohr-Verschraubungen inclusive Zubeh\u00f6r, sowie Metallschl\u00e4uche und darauf abgestimmte Schlauchverschraubungen, zus\u00e4tzlich Kabelverschraubungen mit Zubeh\u00f6r.","link":"https:\/\/www.lagra.de\/en\/sonderanwendungen\/bahn\/","name":"Railway","slug":"bahn","taxonomy":"sonderanwendungen","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lagra.de\/en\/wp-json\/wp\/v2\/sonderanwendungen\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lagra.de\/en\/wp-json\/wp\/v2\/sonderanwendungen"}],"about":[{"href":"https:\/\/www.lagra.de\/en\/wp-json\/wp\/v2\/taxonomies\/sonderanwendungen"}],"wp:post_type":[{"href":"https:\/\/www.lagra.de\/en\/wp-json\/wp\/v2\/lagra-produkte?sonderanwendungen=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}